{"id":19157,"date":"2025-08-18T11:55:34","date_gmt":"2025-08-18T09:55:34","guid":{"rendered":"https:\/\/zentrum-fuer-kunst.de\/?post_type=kw-event&#038;p=19157"},"modified":"2025-09-10T10:05:28","modified_gmt":"2025-09-10T08:05:28","slug":"kulturmosaik","status":"publish","type":"kw-event","link":"https:\/\/zentrum-fuer-kunst.de\/en\/kw-event\/kulturmosaik\/","title":{"rendered":"Kulturmosaik"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"19157\" class=\"elementor elementor-19157\" data-elementor-post-type=\"kw-event\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e06f91c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e06f91c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bf8c879\" data-id=\"bf8c879\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9173a36 elementor-widget elementor-widget-spacer\" data-id=\"9173a36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e91b8dc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e91b8dc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0e9e16e\" data-id=\"0e9e16e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dfec310 elementor-widget elementor-widget-heading\" data-id=\"dfec310\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Filmpr\u00e4sentationen mit Get-Together<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fe02329 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fe02329\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-23ccac0\" data-id=\"23ccac0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1cc8e8e elementor-widget elementor-widget-text-editor\" data-id=\"1cc8e8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>W\u00e4hrend der Corona-Krise 2020 startete das Filmb\u00fcro die\u00a0<a href=\"https:\/\/www.filmbuero-bremen.de\/kulturmosaik\/\">Filmreihe KULTURMOSAIK<\/a>\u00a0als Hilfsma\u00dfnahme f\u00fcr die Bremer Filmszene. Bremer Filmemacher:innen wurden aufgerufen, Kurzportraits Bremer Kulturschaffender zu produzieren. Angesichts des Budgets erwartete man kleine Filme mit kleinem Aufwand. Was herauskam, waren oft herausragende Portraits mit Autor:innenhandschrift, die nicht nur inhaltlich vom Reichtum der Bremer Kulturszene zeugten. Sie zeigten auch das gro\u00dfe filmische Talent, das die Stadt Bremen zu bieten hat und wurden damit auch zu Selbstportraits der Portraitierenden.<\/p><p>F\u00fcnf Jahre nach dem ersten Kulturmosaik sind \u2013 dank der Projektmittelf\u00f6rderung durch den Senator f\u00fcr Kultur \u2013 17 Portraits \u00fcber Bremer K\u00fcnstler:innen aus fast jeder Sparte entstanden. Und es gibt weiteres gro\u00dfes Potential f\u00fcr diese Filmform in der Stadt. Durch die sukzessive Entstehung der Portraits wurden zwar einzelne Filme, aber die Reihe als solche noch nicht \u00f6ffentlich pr\u00e4sentiert. Es wird Zeit dies nachzuholen und alle Mitwirkenden und Interessierten auch jenseits der Leinwand zusammenzubringen. Deshalb l\u00e4dt das Filmb\u00fcro, zu einem Abend mit ausgew\u00e4hlten Kulturmosaiken ins Zentrum f\u00fcr Kunst. Als besonderes Highlight gibt es eine Filmpremiere.<\/p><p>Filmemacher:innen und Portraitierte werden vor Ort sein und hoffen, bei Sekt, O-Saft und einem kleinen Snack anschlie\u00dfend mit den G\u00e4sten ins Gespr\u00e4ch zu kommen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c63cfd2\" data-id=\"c63cfd2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc88ca8 elementor-widget elementor-widget-image\" data-id=\"cc88ca8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/zentrum-fuer-kunst.de\/wp-content\/uploads\/2025\/08\/kulturmosaik.Titelbild-768x432.jpg\" class=\"attachment-medium_large size-medium_large wp-image-19162\" alt=\"\" srcset=\"https:\/\/zentrum-fuer-kunst.de\/wp-content\/uploads\/2025\/08\/kulturmosaik.Titelbild-768x432.jpg 768w, https:\/\/zentrum-fuer-kunst.de\/wp-content\/uploads\/2025\/08\/kulturmosaik.Titelbild-300x169.jpg 300w, https:\/\/zentrum-fuer-kunst.de\/wp-content\/uploads\/2025\/08\/kulturmosaik.Titelbild-1024x576.jpg 1024w, https:\/\/zentrum-fuer-kunst.de\/wp-content\/uploads\/2025\/08\/kulturmosaik.Titelbild-1536x864.jpg 1536w, https:\/\/zentrum-fuer-kunst.de\/wp-content\/uploads\/2025\/08\/kulturmosaik.Titelbild-18x10.jpg 18w, https:\/\/zentrum-fuer-kunst.de\/wp-content\/uploads\/2025\/08\/kulturmosaik.Titelbild-600x338.jpg 600w, https:\/\/zentrum-fuer-kunst.de\/wp-content\/uploads\/2025\/08\/kulturmosaik.Titelbild.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcdb8f4 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"bcdb8f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 2\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/zentrum-fuer-kunst.de\/wp-content\/uploads\/2025\/08\/Filmportrait-Ulf-Nawrot_copyright-famose-filme-768x432.jpeg\" alt=\"Filmportrait \u00fcber Ulf Nawrot von famose filme, copyright famose filme\" \/><figcaption class=\"elementor-image-carousel-caption\">Filmportrait \u00fcber Ulf Nawrot von famose filme, copyright famose filme<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 2\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/zentrum-fuer-kunst.de\/wp-content\/uploads\/2025\/08\/Filmportrait-Gudrun-Schleisinger_copyright-Monika-B-Beyer-768x412.png\" alt=\"Filmportrait \u00fcber  Gudrun Schleisinger von Monika B. Beyer, copyright Monika B. Beyer\" \/><figcaption class=\"elementor-image-carousel-caption\">Filmportrait \u00fcber  Gudrun Schleisinger von Monika B. Beyer, copyright Monika B. Beyer<\/figcaption><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cbbcb42 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cbbcb42\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8c3c18e\" data-id=\"8c3c18e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb5147c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"cb5147c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19804b1 elementor-widget elementor-widget-toggle\" data-id=\"19804b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2671\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2671\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00dcber die Filmreihe \"Kulturmosaik\"<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2671\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2671\" data-no-translation=\"\" data-trp-gettext=\"\"><p>Die dokumentarische Kurzfilmreihe \u201eKulturmosaik\u201c vom Filmb\u00fcro enstand in enger Zusammenarbeit mit den Verb\u00e4nden der freien K\u00fcnste in Bremen. Bislang wurden 16 Portr\u00e4ts \u00fcber Akteur:innen u.a. aus Literatur, Bildende Kunst, Musik und Film realisiert. Die Filme wurden von Bremer Filmschaffenden gedreht, die im Austausch mit den Portr\u00e4tierten f\u00fcr jeden Film ein individuelles Konzept entworfen haben.<\/p><p>Idee und Zweck der Reihe ist es, Bremer K\u00fcnstler:innen und Kulturschaffende vorzustellen und den Facettenreichtum, die Professionalit\u00e4t und die Kreativit\u00e4t der lokalen Kulturszene auf sensible, \u00fcberraschende, informative und unterhaltsame Weise einzufangen. Das Ziel ist keine Vollst\u00e4ndigkeit, sondern ein bunt zusammengesetztes Mosaik verschiedenster Aspekte einer sehr lebendigen freien Szene und der Menschen, die diese durch ihre k\u00fcnstlerische Arbeit mit Leben f\u00fcllen.<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>F\u00fcnf Jahre nach Start der Dokumentationsreihe Kulturmosaik l\u00e4dt das filmb\u00fcro Bremen alle Portr\u00e4tierten und Filmemacher zu einem gemeinsamen Abend ein, an dem bekannte und ein neuer Kurzfilm gezeigt werden.<\/p>","protected":false},"featured_media":19158,"template":"","meta":{"_tbt_post_transparent":"","_tbt_post_title":"hide","_tbt_post_layout":"fullwidth","_tbt_post_sidebar_id":"","_tbt_post_content_style":"unboxed","_tbt_post_vertical_padding":"hide","_tbt_post_feature":"hide","_tbt_post_feature_position":"","_tbt_post_header":false,"_tbt_post_footer":false},"kw_event_category":[293],"kw_event_thema":[201],"class_list":["post-19157","kw-event","type-kw-event","status-publish","has-post-thumbnail","hentry","kw_event_category-film","kw_event_thema-kulturszene-bremen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kulturmosaik - Zentrum f\u00fcr Kunst<\/title>\n<meta name=\"description\" content=\"F\u00fcnf Jahre nach Start der Dokumentationsreihe Kulturmosaik l\u00e4dt das filmb\u00fcro Bremen alle Portr\u00e4tierten und Filmemacher zu einem gemeinsamen Abend ein, an dem bekannte und ein neuer Kurzfilm gezeigt werden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zentrum-fuer-kunst.de\/en\/kw-event\/kulturmosaik\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kulturmosaik - Zentrum f\u00fcr Kunst\" \/>\n<meta property=\"og:description\" content=\"F\u00fcnf Jahre nach Start der Dokumentationsreihe Kulturmosaik l\u00e4dt das filmb\u00fcro Bremen alle Portr\u00e4tierten und Filmemacher zu einem gemeinsamen Abend ein, an dem bekannte und ein neuer Kurzfilm gezeigt werden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zentrum-fuer-kunst.de\/en\/kw-event\/kulturmosaik\/\" \/>\n<meta property=\"og:site_name\" content=\"Zentrum f\u00fcr Kunst\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-10T08:05:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zentrum-fuer-kunst.de\/wp-content\/uploads\/2025\/08\/Filmportrait-Ulf-Nawrot_copyright-famose-filme-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zentrum-fuer-kunst.de\\\/en\\\/kw-event\\\/kulturmosaik\\\/\",\"url\":\"https:\\\/\\\/zentrum-fuer-kunst.de\\\/en\\\/kw-event\\\/kulturmosaik\\\/\",\"name\":\"Kulturmosaik - Zentrum f\u00fcr Kunst\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zentrum-fuer-kunst.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zentrum-fuer-kunst.de\\\/en\\\/kw-event\\\/kulturmosaik\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zentrum-fuer-kunst.de\\\/en\\\/kw-event\\\/kulturmosaik\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zentrum-fuer-kunst.de\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Filmportrait-Ulf-Nawrot_copyright-famose-filme-scaled.jpeg\",\"datePublished\":\"2025-08-18T09:55:34+00:00\",\"dateModified\":\"2025-09-10T08:05:28+00:00\",\"description\":\"F\u00fcnf Jahre nach Start der Dokumentationsreihe Kulturmosaik l\u00e4dt das filmb\u00fcro Bremen alle Portr\u00e4tierten und Filmemacher zu einem gemeinsamen Abend ein, an dem bekannte und ein neuer Kurzfilm gezeigt werden.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zentrum-fuer-kunst.de\\\/en\\\/kw-event\\\/kulturmosaik\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zentrum-fuer-kunst.de\\\/en\\\/kw-event\\\/kulturmosaik\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/zentrum-fuer-kunst.de\\\/en\\\/kw-event\\\/kulturmosaik\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zentrum-fuer-kunst.de\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Filmportrait-Ulf-Nawrot_copyright-famose-filme-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/zentrum-fuer-kunst.de\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Filmportrait-Ulf-Nawrot_copyright-famose-filme-scaled.jpeg\",\"width\":2560,\"height\":1440,\"caption\":\"Filmportrait \u00fcber Ulf Nawrot von famose filme, copyright famose filme\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zentrum-fuer-kunst.de\\\/en\\\/kw-event\\\/kulturmosaik\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"zfk events\",\"item\":\"https:\\\/\\\/zentrum-fuer-kunst.de\\\/kw-event\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kulturmosaik\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zentrum-fuer-kunst.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/zentrum-fuer-kunst.de\\\/en\\\/\",\"name\":\"Zentrum f\u00fcr Kunst\",\"description\":\"B\u00fchnen und Ateliers f\u00fcr die Freie Kunst-Szene Bremen.\",\"publisher\":{\"@id\":\"https:\\\/\\\/zentrum-fuer-kunst.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zentrum-fuer-kunst.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zentrum-fuer-kunst.de\\\/en\\\/#organization\",\"name\":\"Zentrum f\u00fcr Kunst\",\"url\":\"https:\\\/\\\/zentrum-fuer-kunst.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/zentrum-fuer-kunst.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zentrum-fuer-kunst.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-Logo_Zentrum_fuer_Kunst_weiss-2.png\",\"contentUrl\":\"https:\\\/\\\/zentrum-fuer-kunst.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-Logo_Zentrum_fuer_Kunst_weiss-2.png\",\"width\":767,\"height\":290,\"caption\":\"Zentrum f\u00fcr Kunst\"},\"image\":{\"@id\":\"https:\\\/\\\/zentrum-fuer-kunst.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kulturmosaik - Zentrum f\u00fcr Kunst","description":"F\u00fcnf Jahre nach Start der Dokumentationsreihe Kulturmosaik l\u00e4dt das filmb\u00fcro Bremen alle Portr\u00e4tierten und Filmemacher zu einem gemeinsamen Abend ein, an dem bekannte und ein neuer Kurzfilm gezeigt werden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zentrum-fuer-kunst.de\/en\/kw-event\/kulturmosaik\/","og_locale":"en_GB","og_type":"article","og_title":"Kulturmosaik - Zentrum f\u00fcr Kunst","og_description":"F\u00fcnf Jahre nach Start der Dokumentationsreihe Kulturmosaik l\u00e4dt das filmb\u00fcro Bremen alle Portr\u00e4tierten und Filmemacher zu einem gemeinsamen Abend ein, an dem bekannte und ein neuer Kurzfilm gezeigt werden.","og_url":"https:\/\/zentrum-fuer-kunst.de\/en\/kw-event\/kulturmosaik\/","og_site_name":"Zentrum f\u00fcr Kunst","article_modified_time":"2025-09-10T08:05:28+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/zentrum-fuer-kunst.de\/wp-content\/uploads\/2025\/08\/Filmportrait-Ulf-Nawrot_copyright-famose-filme-scaled.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zentrum-fuer-kunst.de\/en\/kw-event\/kulturmosaik\/","url":"https:\/\/zentrum-fuer-kunst.de\/en\/kw-event\/kulturmosaik\/","name":"Kulturmosaik - Zentrum f\u00fcr Kunst","isPartOf":{"@id":"https:\/\/zentrum-fuer-kunst.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zentrum-fuer-kunst.de\/en\/kw-event\/kulturmosaik\/#primaryimage"},"image":{"@id":"https:\/\/zentrum-fuer-kunst.de\/en\/kw-event\/kulturmosaik\/#primaryimage"},"thumbnailUrl":"https:\/\/zentrum-fuer-kunst.de\/wp-content\/uploads\/2025\/08\/Filmportrait-Ulf-Nawrot_copyright-famose-filme-scaled.jpeg","datePublished":"2025-08-18T09:55:34+00:00","dateModified":"2025-09-10T08:05:28+00:00","description":"F\u00fcnf Jahre nach Start der Dokumentationsreihe Kulturmosaik l\u00e4dt das filmb\u00fcro Bremen alle Portr\u00e4tierten und Filmemacher zu einem gemeinsamen Abend ein, an dem bekannte und ein neuer Kurzfilm gezeigt werden.","breadcrumb":{"@id":"https:\/\/zentrum-fuer-kunst.de\/en\/kw-event\/kulturmosaik\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zentrum-fuer-kunst.de\/en\/kw-event\/kulturmosaik\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/zentrum-fuer-kunst.de\/en\/kw-event\/kulturmosaik\/#primaryimage","url":"https:\/\/zentrum-fuer-kunst.de\/wp-content\/uploads\/2025\/08\/Filmportrait-Ulf-Nawrot_copyright-famose-filme-scaled.jpeg","contentUrl":"https:\/\/zentrum-fuer-kunst.de\/wp-content\/uploads\/2025\/08\/Filmportrait-Ulf-Nawrot_copyright-famose-filme-scaled.jpeg","width":2560,"height":1440,"caption":"Filmportrait \u00fcber Ulf Nawrot von famose filme, copyright famose filme"},{"@type":"BreadcrumbList","@id":"https:\/\/zentrum-fuer-kunst.de\/en\/kw-event\/kulturmosaik\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"zfk events","item":"https:\/\/zentrum-fuer-kunst.de\/kw-event\/"},{"@type":"ListItem","position":2,"name":"Kulturmosaik"}]},{"@type":"WebSite","@id":"https:\/\/zentrum-fuer-kunst.de\/en\/#website","url":"https:\/\/zentrum-fuer-kunst.de\/en\/","name":"Zentrum f\u00fcr Kunst","description":"B\u00fchnen und Ateliers f\u00fcr die Freie Kunst-Szene Bremen.","publisher":{"@id":"https:\/\/zentrum-fuer-kunst.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zentrum-fuer-kunst.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/zentrum-fuer-kunst.de\/en\/#organization","name":"Zentrum f\u00fcr Kunst","url":"https:\/\/zentrum-fuer-kunst.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/zentrum-fuer-kunst.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/zentrum-fuer-kunst.de\/wp-content\/uploads\/2023\/07\/cropped-Logo_Zentrum_fuer_Kunst_weiss-2.png","contentUrl":"https:\/\/zentrum-fuer-kunst.de\/wp-content\/uploads\/2023\/07\/cropped-Logo_Zentrum_fuer_Kunst_weiss-2.png","width":767,"height":290,"caption":"Zentrum f\u00fcr Kunst"},"image":{"@id":"https:\/\/zentrum-fuer-kunst.de\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/zentrum-fuer-kunst.de\/en\/wp-json\/wp\/v2\/kw-event\/19157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zentrum-fuer-kunst.de\/en\/wp-json\/wp\/v2\/kw-event"}],"about":[{"href":"https:\/\/zentrum-fuer-kunst.de\/en\/wp-json\/wp\/v2\/types\/kw-event"}],"version-history":[{"count":16,"href":"https:\/\/zentrum-fuer-kunst.de\/en\/wp-json\/wp\/v2\/kw-event\/19157\/revisions"}],"predecessor-version":[{"id":19696,"href":"https:\/\/zentrum-fuer-kunst.de\/en\/wp-json\/wp\/v2\/kw-event\/19157\/revisions\/19696"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zentrum-fuer-kunst.de\/en\/wp-json\/wp\/v2\/media\/19158"}],"wp:attachment":[{"href":"https:\/\/zentrum-fuer-kunst.de\/en\/wp-json\/wp\/v2\/media?parent=19157"}],"wp:term":[{"taxonomy":"kw_event_category","embeddable":true,"href":"https:\/\/zentrum-fuer-kunst.de\/en\/wp-json\/wp\/v2\/kw_event_category?post=19157"},{"taxonomy":"kw_event_thema","embeddable":true,"href":"https:\/\/zentrum-fuer-kunst.de\/en\/wp-json\/wp\/v2\/kw_event_thema?post=19157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}